{"id":121631,"date":"2025-12-02T09:27:26","date_gmt":"2025-12-02T08:27:26","guid":{"rendered":"https:\/\/poggi.tesecom.net\/prodotto\/decantatori-dinamici\/"},"modified":"2026-05-04T17:18:15","modified_gmt":"2026-05-04T15:18:15","slug":"decanteurs-dynamiques","status":"publish","type":"prodotto","link":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/","title":{"rendered":"D\u00e9canteurs dynamiques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"121631\" class=\"elementor elementor-121631 elementor-116129\" data-elementor-post-type=\"prodotto\">\n\t\t\t\t<div class=\"elementor-element elementor-element-545896f e-flex e-con-boxed e-con e-parent\" data-id=\"545896f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e1e06 e-flex e-con-boxed e-con e-parent\" data-id=\"65e1e06\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69107ec elementor-widget elementor-widget-breadcrumbs\" data-id=\"69107ec\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/poggi.tesecom.net\/fr\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dd3a04 e-flex e-con-boxed e-con e-parent\" data-id=\"4dd3a04\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37cd95c elementor-widget elementor-widget-heading\" data-id=\"37cd95c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00c9CANTATEURS DYNAMIQUES<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d46f4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c6d46f4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b890b15 e-flex e-con-boxed e-con e-parent\" data-id=\"b890b15\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5b6b2 elementor-widget elementor-widget-text-editor\" data-id=\"9c5b6b2\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Flux dynamique, efficacit\u00e9 maximale, maintenance r\u00e9duite<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87ba655 e-flex e-con-boxed e-con e-parent\" data-id=\"87ba655\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f26faf3 e-con-full e-flex e-con e-child\" data-id=\"f26faf3\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5abac8 elementor-widget elementor-widget-image\" data-id=\"d5abac8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"791\" height=\"675\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-en-fonctionnement.webp\" class=\"attachment-full size-full wp-image-124214\" alt=\"d\u00e9canteur dynamique en fonctionnement\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-en-fonctionnement.webp 791w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-en-fonctionnement-300x256.webp 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-en-fonctionnement-768x655.webp 768w\" sizes=\"(max-width: 791px) 100vw, 791px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82a3c4f e-con-full e-flex e-con e-child\" data-id=\"82a3c4f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-636a525 elementor-widget elementor-widget-heading\" data-id=\"636a525\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00c9CANTATEURS DYNAMIQUES S\u00c9RIE D-DEC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60b489f elementor-widget elementor-widget-heading\" data-id=\"60b489f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2b27f8 e-con-full e-flex e-con e-child\" data-id=\"e2b27f8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7829c8b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7829c8b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contatto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0f2a4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0c0f2a4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scarica il catalogo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc419ac elementor-widget elementor-widget-text-editor\" data-id=\"cc419ac\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes <strong>d\u00e9cantateurs dynamiques<\/strong> Poggi, \u00e9galement appel\u00e9s <em>s\u00e9dimentateurs dynamiques<\/em>, repr\u00e9sentent la solution id\u00e9ale pour la s\u00e9paration solide-liquide dans les installations industrielles \u00e0 haute intensit\u00e9 op\u00e9rationnelle, o\u00f9 sont requises continuit\u00e9, contr\u00f4le et capacit\u00e9s de traitement \u00e9lev\u00e9es. Gr\u00e2ce \u00e0 leur fonctionnement m\u00e9canis\u00e9 et \u00e0 leur design optimis\u00e9, ils garantissent une s\u00e9dimentation rapide et une gestion efficace des boues.\n\nAdapt\u00e9s \u00e0 une large gamme d\u2019applications, y compris les installations de lavage d\u2019inertes, le traitement des eaux us\u00e9es, la r\u00e9cup\u00e9ration environnementale, le recyclage des sous-produits et l\u2019industrie de la biomasse, les d\u00e9cantateurs dynamiques Poggi s\u2019int\u00e8grent facilement dans des lignes nouvelles ou existantes, assurant flexibilit\u00e9 de l\u2019installation et performances \u00e9lev\u00e9es dans le temps.\n\nLes d\u00e9cantateurs peuvent \u00eatre fabriqu\u00e9s en diff\u00e9rents mat\u00e9riaux et sont con\u00e7us pour r\u00e9sister \u00e0 des conditions s\u00e9v\u00e8res et \u00e0 des cycles de travail intensifs. Le syst\u00e8me dynamique favorise la s\u00e9paration continue des solides, tandis que les sorties d\u00e9di\u00e9es pour l\u2019eau clarifi\u00e9e et les boues permettent une gestion pr\u00e9cise des flux.\nL\u2019int\u00e9gration avec des syst\u00e8mes d\u2019extraction et des syst\u00e8mes de contr\u00f4le num\u00e9rique permet un fonctionnement automatis\u00e9 et personnalisable, m\u00eame au sein d\u2019installations complexes ou d\u2019architectures 4.0. Les \u00e9quipements optionnels incluent des vannes, des capteurs de niveau, des syst\u00e8mes anti-obstruction et des outils pour la gestion \u00e0 distance.\n\nGr\u00e2ce \u00e0 l\u2019exp\u00e9rience de Poggi, les d\u00e9cantateurs dynamiques peuvent \u00eatre adapt\u00e9s aux besoins op\u00e9rationnels du client, avec possibilit\u00e9 d\u2019extension ou de modification au fil du temps.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c313d4 e-flex e-con-boxed e-con e-parent\" data-id=\"0c313d4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e80525c elementor-widget elementor-widget-text-editor\" data-id=\"e80525c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>D\u00e9cantateurs Poggi, depuis toujours, le choix professionnel<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ee7809 e-con-full e-flex e-con e-child\" data-id=\"8ee7809\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-79d0bbd e-con-full e-flex e-con e-child\" data-id=\"79d0bbd\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-640c8aa elementor-widget elementor-widget-text-editor\" data-id=\"640c8aa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span> <\/strong>Structure galvanis\u00e9e ou peinte, avec parties en contact avec le liquide \u00e0 s\u00e9dimenter personnalisables en diff\u00e9rents mat\u00e9riaux et finitions\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Syst\u00e8me dynamique de s\u00e9paration avec organes en mouvement, pour une gestion constante et contr\u00f4l\u00e9e des boues\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> D\u00e9chargement automatique du mat\u00e9riau d\u00e9cant\u00e9, programmable selon des cycles ou en fonction des d\u00e9bits effectifs\n<span style=\"color: #1a94d2;\"><strong>><\/strong><\/span> Int\u00e9gration maximale avec pompes, silos \u00e0 boues, presse \u00e0 filtre et syst\u00e8mes de traitement ult\u00e9rieurs\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a79dd9 e-con-full e-flex e-con e-child\" data-id=\"5a79dd9\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39c28d3 elementor-widget elementor-widget-text-editor\" data-id=\"39c28d3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> R\u00e9sistance aux agents atmosph\u00e9riques et aux contraintes m\u00e9caniques\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Compatibles avec des solutions d\u2019automatisation et interfa\u00e7ables avec des architectures Industrie 4.0\n\n<strong><span style=\"color: #1a94d2;\">><\/span> <\/strong>Id\u00e9aux pour les installations \u00e0 grands volumes, avec variabilit\u00e9 des mat\u00e9riaux et besoins d\u2019interventions op\u00e9rationnelles r\u00e9duites\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1de962b e-flex e-con-boxed e-con e-parent\" data-id=\"1de962b\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80ae2b3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"80ae2b3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-487e31d e-flex e-con-boxed e-con e-parent\" data-id=\"487e31d\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-231d5fb e-con-full e-flex e-con e-child\" data-id=\"231d5fb\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3fafa7 elementor-widget elementor-widget-heading\" data-id=\"b3fafa7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Polyvalence d\u2019application<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc313a elementor-widget elementor-widget-heading\" data-id=\"5cc313a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une solution, de multiples secteurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83916c0 elementor-widget elementor-widget-text-editor\" data-id=\"83916c0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes <strong>d\u00e9cantateurs dynamiques<\/strong> Poggi repr\u00e9sentent une solution avanc\u00e9e et haute performance pour la s\u00e9paration solide-liquide dans les processus industriels. Gr\u00e2ce \u00e0 la pr\u00e9sence de composants internes en mouvement, ils assurent une s\u00e9dimentation acc\u00e9l\u00e9r\u00e9e et une extraction contr\u00f4l\u00e9e des boues, m\u00eame en conditions de charge intense ou en pr\u00e9sence de mat\u00e9riaux difficiles. Ces caract\u00e9ristiques rendent le <strong>d\u00e9cantateur dynamique<\/strong> adapt\u00e9 \u00e0 une grande vari\u00e9t\u00e9 d\u2019applications et de contextes op\u00e9rationnels, offrant une polyvalence \u00e9lev\u00e9e dans les diff\u00e9rents secteurs industriels.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2aeaa elementor-widget elementor-widget-text-editor\" data-id=\"3d2aeaa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Installations de b\u00e9tonnage pour la s\u00e9paration continue des boues provenant du lavage des inertes et le recyclage des eaux de process\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Industrie chimique, environnementale et agricole pour le traitement automatique des effluents contenant des boues, des r\u00e9sidus de r\u00e9action ou des particules en suspension\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> R\u00e9cup\u00e9ration environnementale et recyclage pour la d\u00e9cantation m\u00e9canis\u00e9e des sous-produits solides dans des contextes \u00e0 haute intensit\u00e9 op\u00e9rationnelle\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Industrie du plastique pour la s\u00e9paration dynamique des particules r\u00e9siduelles dans les eaux de process et la gestion contr\u00f4l\u00e9e des boues non dangereuses\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Production d\u2019\u00e9nergie \u00e0 partir de biomasses ou de d\u00e9chets organiques pour le traitement des liquides de process et des eaux de lavage contenant des r\u00e9sidus solides\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-558d19d e-con-full e-flex e-con e-child\" data-id=\"558d19d\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5c870 elementor-widget elementor-widget-image\" data-id=\"9c5c870\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique.webp\" class=\"attachment-large size-large wp-image-124216\" alt=\"d\u00e9canteur dynamique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ead1fb4 e-flex e-con-boxed e-con e-parent\" data-id=\"ead1fb4\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccbf73f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ccbf73f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d059f39 e-flex e-con-boxed e-con e-parent\" data-id=\"d059f39\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08757bd elementor-widget elementor-widget-text-editor\" data-id=\"08757bd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Fonctionnement et s\u00e9curit\u00e9<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c39f6e elementor-widget elementor-widget-text-editor\" data-id=\"5c39f6e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes d\u00e9cantateurs dynamiques Poggi sont con\u00e7us pour la s\u00e9paration continue solide\u2011liquide via un processus m\u00e9canis\u00e9 qui acc\u00e9l\u00e8re la s\u00e9dimentation des solides en suspension. Le flux entrant est dirig\u00e9 dans la cuve par un tube d\u2019alimentation qui introduit le liquide dans la partie inf\u00e9rieure du d\u00e9cantateur, favorisant un remplissage contr\u00f4l\u00e9 et une distribution uniforme du flux.\n\n\u00c0 l\u2019int\u00e9rieur du d\u00e9cantateur, les r\u00e2teaux rotatifs collectent et dirigent le mat\u00e9riau s\u00e9diment\u00e9 vers le point de d\u00e9charge, garantissant une s\u00e9dimentation uniforme et continue. Le syst\u00e8me peut \u00eatre pr\u00e9par\u00e9 pour l\u2019injection de floculants via des points de dosage int\u00e9gr\u00e9s, favorisant l\u2019agr\u00e9gation des particules fines et am\u00e9liorant la vitesse de s\u00e9paration.\n\nLes solides s\u00e9par\u00e9s sont \u00e9vacu\u00e9s via une sortie d\u00e9di\u00e9e et dirig\u00e9s, par exemple, vers des syst\u00e8mes de collecte de boues ou des syst\u00e8mes de d\u00e9shydratation. L\u2019eau clarifi\u00e9e, s\u00e9par\u00e9e du mat\u00e9riau s\u00e9diment\u00e9, remonte et est recueillie via un syst\u00e8me de trop-plein p\u00e9riph\u00e9rique, reli\u00e9 \u00e0 un conduit de d\u00e9charge pour une gestion ou r\u00e9utilisation ult\u00e9rieure.\n\nLe syst\u00e8me dynamique permet une gestion continue et automatis\u00e9e du processus, r\u00e9duisant les temps de cycle et augmentant l\u2019efficacit\u00e9, tout en maintenant une structure compacte facilement int\u00e9grable dans des lignes de production existantes.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1241b8a elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1241b8a\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9db6fcf elementor-widget elementor-widget-elementskit-hotspot\" data-id=\"9db6fcf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"ekit-location-groups\" data-breakpoints=\"{&quot;mobile&quot;:767,&quot;tablet&quot;:1024}\">\n            <div class=\"ekit-map-image text-center\">\n                <img decoding=\"async\" width=\"1334\" height=\"1110\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-Poggi-spa.webp\" class=\"attachment-full size-full\" alt=\"d\u00e9canteur dynamique Poggi spa\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-Poggi-spa.webp 1334w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-Poggi-spa-300x250.webp 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-Poggi-spa-1024x852.webp 1024w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-Poggi-spa-768x639.webp 768w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/>            <\/div>\n            <div class=\"ekit-location-wraper clearfix\">\n                \n<div class=\"ekit-location elementor-repeater-item-1c7e8e6 ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">FOND CONIQUE<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>La partie inf\u00e9rieure du d\u00e9cantateur dynamique est constitu\u00e9e d\u2019un fond conique, con\u00e7u pour favoriser la concentration et l\u2019acheminement des solides vers le centre. Dans cette zone, des r\u00e2teaux rotatifs agissent comme des racloirs, dirigeant le mat\u00e9riau s\u00e9diment\u00e9 vers le point de d\u00e9charge, favorisant une collecte uniforme et continue.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n<div class=\"ekit-location elementor-repeater-item-798c950 ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">SYST\u00c8ME DE ROTATION<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>Les r\u00e2teaux install\u00e9s \u00e0 l\u2019int\u00e9rieur du d\u00e9canteur sont con\u00e7us pour s\u2019adapter aux caract\u00e9ristiques sp\u00e9cifiques du mat\u00e9riau \u00e0 traiter. Ils peuvent \u00eatre personnalis\u00e9s en forme, en g\u00e9om\u00e9trie et en mat\u00e9riau de construction (acier inoxydable, anti\u2011usure, plastifi\u00e9, etc.) selon la densit\u00e9, la granulom\u00e9trie et la nature chimique de l\u2019effluent. Cette possibilit\u00e9 de configuration permet d\u2019optimiser les performances et la dur\u00e9e de vie du d\u00e9canteur.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n<div class=\"ekit-location elementor-repeater-item-aa874dd ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">JOINTS D\u2019\u00c9TANCH\u00c9IT\u00c9<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\"><div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\"><div class=\"flex max-w-full flex-col gap-4 grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\"><div class=\"flex w-full flex-col gap-1 empty:hidden\"><div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\"><p>Les joints, positionn\u00e9s aux points de jonction entre les diff\u00e9rents panneaux constituant le d\u00e9cantateur, jouent un r\u00f4le essentiel : ils doivent r\u00e9sister \u00e0 l\u2019usure et offrir une protection contre les agents atmosph\u00e9riques. Les mat\u00e9riaux choisis par Poggi garantissent une \u00e9tanch\u00e9it\u00e9 \u00e9lev\u00e9e dans le temps, contribuant \u00e0 la stabilit\u00e9 et \u00e0 l\u2019efficacit\u00e9 globale de la structure.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n<div class=\"ekit-location elementor-repeater-item-263cf4a ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">COLLECTE DE L\u2019EAU CLARIFI\u00c9E<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>L\u2019eau s\u00e9par\u00e9e remonte vers la partie sup\u00e9rieure du d\u00e9cantateur, o\u00f9 elle est collect\u00e9e par un syst\u00e8me de trop-plein p\u00e9riph\u00e9rique et dirig\u00e9e dans le conduit de d\u00e9charge. Cela assure un \u00e9coulement continu et contr\u00f4l\u00e9 du liquide clarifi\u00e9, pr\u00eat \u00e0 \u00eatre r\u00e9utilis\u00e9 ou trait\u00e9 dans les \u00e9tapes suivantes.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>            <\/div><!-- .location-wraper END -->\n        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b821372 e-flex e-con-boxed e-con e-parent\" data-id=\"b821372\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-402988e elementor-widget elementor-widget-heading\" data-id=\"402988e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gestion des flux de mat\u00e9riau<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1005983 e-flex e-con-boxed e-con e-parent\" data-id=\"1005983\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b05f68b e-con-full e-flex e-con e-child\" data-id=\"b05f68b\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-025f097 elementor-widget elementor-widget-heading\" data-id=\"025f097\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">D\u00c9CHARGEMENT<\/span> DES BOUDES\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3cfe2b elementor-widget elementor-widget-text-editor\" data-id=\"b3cfe2b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">SYST\u00c8ME DE S\u00c9PARATION ACTIVE<\/span><\/strong>\nDans les d\u00e9cantateurs dynamiques Poggi, le processus de s\u00e9paration solide\u2011liquide est assist\u00e9 par des composants m\u00e9caniques actifs qui acc\u00e9l\u00e8rent la d\u00e9cantation et am\u00e9liorent l\u2019efficacit\u00e9 du traitement. L\u2019action dynamique favorise une s\u00e9dimentation plus rapide et contr\u00f4l\u00e9e, m\u00eame avec des boues \u00e0 haute densit\u00e9 ou \u00e0 forte variabilit\u00e9.\n\n<strong><span style=\"color: #1a94d2;\">D\u00c9CHARGEMENT AUTOMATIS\u00c9 \u00c0 CYCLE PROGRAMMABLE<\/span><\/strong>\nLes boues accumul\u00e9es sont \u00e9vacu\u00e9es via un syst\u00e8me automatique de d\u00e9charge situ\u00e9 \u00e0 la base du d\u00e9cantateur. Le cycle de vidage peut \u00eatre r\u00e9gl\u00e9 \u00e0 l\u2019aide de minuterie, de capteurs de niveau ou de commandes \u00e0 distance, garantissant flexibilit\u00e9 op\u00e9rationnelle et continuit\u00e9 des processus en aval.\n\n<strong><span style=\"color: #1a94d2;\">INT\u00c9GRATION AVEC LES INSTALLATIONS DE D\u00c9SHYDRATATION<\/span><\/strong>\nLa d\u00e9charge est con\u00e7ue pour se connecter directement aux pompes, silos \u00e0 boues, presses \u00e0 filtre ou autres unit\u00e9s de traitement. Cela facilite l\u2019automatisation de l\u2019ensemble du processus et optimise la gestion des sous-produits, r\u00e9duisant la charge de travail manuelle.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57ca1b1 e-con-full e-flex e-con e-child\" data-id=\"57ca1b1\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-019d9d4 elementor-widget elementor-widget-image\" data-id=\"019d9d4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-avec-cuve-de-collecte-des-boues.webp\" class=\"attachment-large size-large wp-image-124213\" alt=\"d\u00e9canteur dynamique avec cuve de collecte des boues\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-avec-cuve-de-collecte-des-boues.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteur-dynamique-avec-cuve-de-collecte-des-boues-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b85695 e-flex e-con-boxed e-con e-parent\" data-id=\"1b85695\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5a95ab e-con-full e-flex e-con e-child\" data-id=\"e5a95ab\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f70e62f elementor-widget elementor-widget-image\" data-id=\"f70e62f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-dynamiques-Poggi-spa.webp\" class=\"attachment-large size-large wp-image-124217\" alt=\"d\u00e9canteurs dynamiques Poggi spa\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-dynamiques-Poggi-spa.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-dynamiques-Poggi-spa-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee205ee e-con-full e-flex e-con e-child\" data-id=\"ee205ee\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89287a9 elementor-widget elementor-widget-heading\" data-id=\"89287a9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">INT\u00c9GRATION<\/span> INSTALLATION\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13db0b2 elementor-widget elementor-widget-text-editor\" data-id=\"13db0b2\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">CONNEXION AUX POMPES D\u2019EXTRACTION<\/span><\/strong>\nLes d\u00e9cantateurs dynamiques Poggi peuvent \u00eatre \u00e9quip\u00e9s de raccords d\u00e9di\u00e9s pour pompes submersibles ou pompes de transfert de boues, facilitant le passage direct vers les installations de traitement en aval sans interruption du cycle op\u00e9rationnel.\n\n<strong><span style=\"color: #1a94d2;\">S\u00c9CURIT\u00c9 OP\u00c9RATIONNELLE ET FLUX CONTR\u00d4L\u00c9<\/span><\/strong>\nDes clapets anti-retour, des capteurs de niveau et des contr\u00f4les num\u00e9riques int\u00e9gr\u00e9s garantissent la continuit\u00e9 et la s\u00e9curit\u00e9 op\u00e9rationnelle m\u00eame dans des conditions intensives, pr\u00e9venant les blocages et les obstructions.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a32c797 e-flex e-con-boxed e-con e-parent\" data-id=\"a32c797\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a540948 e-con-full e-flex e-con e-child\" data-id=\"a540948\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b4bcb elementor-widget elementor-widget-heading\" data-id=\"97b4bcb\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">GESTION<\/span> ET CONTR\u00d4LE OP\u00c9RATIONNEL<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4696f elementor-widget elementor-widget-text-editor\" data-id=\"2d4696f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">AUTOMATISATION ET INTERFACE NUM\u00c9RIQUE<\/span><\/strong>\nLes d\u00e9cantateurs dynamiques Poggi peuvent \u00eatre \u00e9quip\u00e9s de capteurs de niveau, d\u00e9bitm\u00e8tres et sondes pour la d\u00e9tection de la densit\u00e9 des boues. Ces dispositifs permettent un suivi en temps r\u00e9el des param\u00e8tres du processus, am\u00e9liorant l\u2019efficacit\u00e9 op\u00e9rationnelle et la planification de la maintenance.\n\n<strong><span style=\"color: #1a94d2;\">FILTRE SUP\u00c9RIEUR<\/span><\/strong>\nIl est possible de connecter le d\u00e9cantateur \u00e0 des syst\u00e8mes de supervision \u00e0 distance (PLC), pour automatiser les op\u00e9rations de d\u00e9charge, r\u00e9gler les cycles de s\u00e9dimentation et int\u00e9grer le fonctionnement avec des pompes, silos \u00e0 boues ou presses \u00e0 filtre. L\u2019interface num\u00e9rique permet \u00e9galement l\u2019archivage des donn\u00e9es et la tra\u00e7abilit\u00e9 des op\u00e9rations.\n\n<strong><span style=\"color: #1a94d2;\">GESTION MANUELLE S\u00dbRE ET EFFICACE<\/span><\/strong>\nPour les contextes o\u00f9 l\u2019automatisation n\u2019est pas prioritaire, le syst\u00e8me peut \u00eatre configur\u00e9 avec des vannes manuelles \u00e0 levier facilement accessibles et robustes. Cette solution assure la fiabilit\u00e9 du s\u00e9dimentateur dynamique m\u00eame en conditions d\u2019utilisation intensive, sans n\u00e9cessiter de composants \u00e9lectroniques.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb07381 e-con-full e-flex e-con e-child\" data-id=\"bb07381\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d471ff elementor-widget elementor-widget-image\" data-id=\"0d471ff\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decantatori-dinamici-installazione.webp\" class=\"attachment-large size-large wp-image-122216\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decantatori-dinamici-installazione.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decantatori-dinamici-installazione-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e43eba8 e-flex e-con-boxed e-con e-parent\" data-id=\"e43eba8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b82f0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a7b82f0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f2772c elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"8f2772c\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfdf3b4 elementor-widget elementor-widget-heading\" data-id=\"dfdf3b4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9tails techniques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc9fcef elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"dc9fcef\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d353adc e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"d353adc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"221592284\" aria-label=\"Onglets. Ouvrez des \u00e9l\u00e9ments avec Entrer ou Espace, fermez-les avec Echape et naviguez \u00e0 l&#039;aide des touches fl\u00e9ch\u00e9es.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2215922841\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2215922841\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs dynamiques D-DEC\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2215922841\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922841\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-7f6667f e-con-full e-flex e-con e-child\" data-id=\"7f6667f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9df4a1b elementor-widget elementor-widget-image\" data-id=\"9df4a1b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1006\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Donnees-Techniques-Serie-D-Dec.webp\" class=\"attachment-medium_large size-medium_large wp-image-126583\" alt=\"D\u00e9canteur Dynamique Donn\u00e9es Techniques S\u00e9rie D Dec\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Donnees-Techniques-Serie-D-Dec.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Donnees-Techniques-Serie-D-Dec-199x300.webp 199w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a09d409 elementor-widget elementor-widget-image\" data-id=\"a09d409\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"161\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Dessin-Technique-300x161.webp\" class=\"attachment-medium size-medium wp-image-126584\" alt=\"D\u00e9canteur Dynamique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Dessin-Technique-300x161.webp 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Dynamique-Dessin-Technique.webp 667w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d187bcd e-flex e-con-boxed e-con e-parent\" data-id=\"d187bcd\" data-element_type=\"container\" id=\"pdf\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d358b9 e-con-full e-flex e-con e-child\" data-id=\"7d358b9\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a5a655 e-con-full e-flex e-con e-child\" data-id=\"9a5a655\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5874bcc e-flex e-con-boxed e-con e-parent\" data-id=\"5874bcc\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83d8e92 e-con-full e-flex e-con e-child\" data-id=\"83d8e92\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c41c5e6 e-con-full e-flex e-con e-child\" data-id=\"c41c5e6\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2784fed elementor-widget elementor-widget-heading\" data-id=\"2784fed\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESSOIRES ET OPTIONS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ad44c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"19ad44c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Une gamme compl\u00e8te d\u2019accessoires et d\u2019options pour personnaliser chaque produit. Des syst\u00e8mes de mesure, de filtration, de s\u00e9curit\u00e9, d\u2019extraction et de contr\u00f4le permettent d\u2019adapter les produits silos aux besoins op\u00e9rationnels sp\u00e9cifiques, garantissant une efficacit\u00e9 maximale et une continuit\u00e9 de fonctionnement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8bd9019 e-con-full e-flex e-con e-child\" data-id=\"8bd9019\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e167f elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"11e167f\" data-element_type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;aee3b0e&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;127c43a&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;1facfc3&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;85f0f52&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;37c733e&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;988cf31&quot;}],&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b966da1 e-flex e-con-boxed e-con e-child\" data-id=\"b966da1\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba8250f elementor-widget elementor-widget-image\" data-id=\"ba8250f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"518\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png\" class=\"attachment-large size-large wp-image-121620\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png 932w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-300x194.png 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-768x498.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fafb040 elementor-widget elementor-widget-heading\" data-id=\"fafb040\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REV\u00caTEMENTS INTERNES SP\u00c9CIAUX<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7a01f8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7a01f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#RIVESTIMENTI_INTERNI_SPECIALI\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7454eb e-flex e-con-boxed e-con e-child\" data-id=\"c7454eb\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-429d983 elementor-widget elementor-widget-image\" data-id=\"429d983\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"518\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png\" class=\"attachment-large size-large wp-image-121620\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png 932w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-300x194.png 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-768x498.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fbe385 elementor-widget elementor-widget-heading\" data-id=\"9fbe385\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SYST\u00c8MES DE CHAUFFAGE OU D\u2019ISOLATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b1d2c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"38b1d2c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#SISTEMI_DI_RISCALDAMENTO_O_COIBENTAZIONE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cda5879 e-flex e-con-boxed e-con e-child\" data-id=\"cda5879\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b517299 elementor-widget elementor-widget-image\" data-id=\"b517299\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp\" class=\"attachment-large size-large wp-image-124109\" alt=\"garde-corps-\u00e9chelles-silos\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4a668 elementor-widget elementor-widget-heading\" data-id=\"ae4a668\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESSOIRES DE S\u00c9CURIT\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afa3e35 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"afa3e35\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#ACCESSORI_DI_SICUREZZA\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3b19f e-flex e-con-boxed e-con e-child\" data-id=\"3e3b19f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66f73dd elementor-widget elementor-widget-image\" data-id=\"66f73dd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique.webp\" class=\"attachment-large size-large wp-image-124095\" alt=\"armoire-\u00e9lectrique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f502f8 elementor-widget elementor-widget-heading\" data-id=\"1f502f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMMANDES \u00c9LECTRIQUES ET INTERFACES OP\u00c9RATOIRES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf85e7f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cf85e7f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#COMANDI_ELETTRICI_E_INTERFACCE_OPERATIVE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8bb7c8 e-flex e-con-boxed e-con e-child\" data-id=\"c8bb7c8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0839d elementor-widget elementor-widget-image\" data-id=\"fb0839d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau.webp\" class=\"attachment-large size-large wp-image-124113\" alt=\"ndicateur-niveau\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f55ff27 elementor-widget elementor-widget-heading\" data-id=\"f55ff27\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTR\u00d4LE DES NIVEAUX ET SURVEILLANCE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-effc55d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"effc55d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#CONTROLLO_LIVELLI_E_MONITORAGGIO\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd48ba8 e-flex e-con-boxed e-con e-child\" data-id=\"bd48ba8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d206a elementor-widget elementor-widget-image\" data-id=\"f4d206a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp\" class=\"attachment-large size-large wp-image-124109\" alt=\"garde-corps-\u00e9chelles-silos\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71bea14 elementor-widget elementor-widget-heading\" data-id=\"71bea14\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fonctionnalit\u00e9s suppl\u00e9mentaires pour la Sant\u00e9 et la S\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5807bd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c5807bd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-dinamici\/#Funzionalit\u00e0_Extra_per_Salute_e_Sicurezza\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f069670 e-flex e-con-boxed e-con e-parent\" data-id=\"f069670\" data-element_type=\"container\" id=\"contatto\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a9fcb0 elementor-widget elementor-widget-heading\" data-id=\"3a9fcb0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACTEZ-NOUS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce0aa4d elementor-button-align-center elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-123119 elementor-global-162 elementor-widget-form\" data-id=\"ce0aa4d\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"121631\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"ce0aa4d\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Poggi S.p.a.\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_a5fb305 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_a5fb305\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCognome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_a5fb305]\" id=\"form-field-field_a5fb305\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Last name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_5d4c6bb elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5d4c6bb\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAzienda\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5d4c6bb]\" id=\"form-field-field_5d4c6bb\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Entreprise\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_8d6aee9 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8d6aee9\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNazione\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_8d6aee9]\" id=\"form-field-field_8d6aee9\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pays\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_f9519d3 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f9519d3\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_f9519d3]\" id=\"form-field-field_f9519d3\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_3ce8930 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3ce8930\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tInscription\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Inscription \u00e0 la newsletter Politique de confidentialit\u00e9\" id=\"form-field-field_3ce8930-0\" name=\"form_fields[field_3ce8930]\"> <label for=\"form-field-field_3ce8930-0\">Inscription \u00e0 la newsletter Politique de confidentialit\u00e9<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_5f5db32 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5f5db32\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tInscription\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_5f5db32]\" id=\"form-field-field_5f5db32\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_5f5db32\">Confidentialit\u00e9 Si vous ne consentez pas au traitement des donn\u00e9es il ne sera pas possible de r\u00e9pondre \u00e0 votre demande.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer une demande<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7305116 e-con-full e-flex e-con e-parent\" data-id=\"7305116\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9653ddf elementor-widget elementor-widget-template\" data-id=\"9653ddf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"122690\" class=\"elementor elementor-122690 elementor-118976 elementor-118976\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2be0d9c4 e-flex e-con-boxed e-con e-parent\" data-id=\"2be0d9c4\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef445d elementor-widget elementor-widget-heading\" data-id=\"2ef445d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u2019inscrire \u00e0 la newsletter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51defb6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"51defb6d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e4b2865 elementor-widget__width-inherit elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"2e4b2865\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"122690\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2e4b2865\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Silos et produits pour stockage de mat\u00e9riaux en vrac | Poggi\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"120158\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Adresse e-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_e04bf5a elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_e04bf5a]\" id=\"form-field-field_e04bf5a\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_e04bf5a\">J\u2019ai pris connaissance de la politique de confidentialit\u00e9 et j\u2019accepte le traitement des donn\u00e9es.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S\u2019inscrire<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>D\u00e9canteurs dynamiques con\u00e7us pour des processus continus de clarification avec grande capacit\u00e9. Offrent un r\u00e9glage pr\u00e9cis, une structure robuste et une excellente efficacit\u00e9 de s\u00e9paration des solides et liquides, garantissant des performances constantes dans des installations \u00e0 haute intensit\u00e9.<\/p>\n","protected":false},"featured_media":123865,"template":"elementor_header_footer","meta":{"_acf_changed":false},"categoria-prodotto":[],"class_list":["post-121631","prodotto","type-prodotto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi<\/title>\n<meta name=\"description\" content=\"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi\" \/>\n<meta property=\"og:description\" content=\"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Poggi S.p.a.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T15:18:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1034\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/\",\"name\":\"D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi\",\"isPartOf\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp\",\"datePublished\":\"2025-12-02T08:27:26+00:00\",\"dateModified\":\"2026-05-04T15:18:15+00:00\",\"description\":\"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.\",\"breadcrumb\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage\",\"url\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp\",\"contentUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp\",\"width\":1034,\"height\":672,\"caption\":\"D\u00e9canteur dynamique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poggi.tesecom.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9canteurs dynamiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#website\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poggi.tesecom.net\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#organization\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"contentUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"width\":1484,\"height\":494,\"caption\":\"Poggi S.p.a. - Produttori di Silos dal 1945\"},\"image\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi","description":"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi","og_description":"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.","og_url":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/","og_site_name":"Poggi S.p.a.","article_modified_time":"2026-05-04T15:18:15+00:00","og_image":[{"width":1034,"height":672,"url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/","url":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/","name":"D\u00e9canteurs dynamiques pour s\u00e9paration solide-liquide | Poggi","isPartOf":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage"},"image":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage"},"thumbnailUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp","datePublished":"2025-12-02T08:27:26+00:00","dateModified":"2026-05-04T15:18:15+00:00","description":"D\u00e9canteurs dynamiques Poggi pour la s\u00e9paration solide-liquide. S\u00e9dimentation rapide, automatisation et gestion efficace des boues.","breadcrumb":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#primaryimage","url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp","contentUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-dynamique.webp","width":1034,"height":672,"caption":"D\u00e9canteur dynamique"},{"@type":"BreadcrumbList","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-dynamiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poggi.tesecom.net\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9canteurs dynamiques"}]},{"@type":"WebSite","@id":"https:\/\/poggi.tesecom.net\/fr\/#website","url":"https:\/\/poggi.tesecom.net\/fr\/","name":"Poggi S.p.a. - Produttori di Silos dal 1945","description":"","publisher":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poggi.tesecom.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/poggi.tesecom.net\/fr\/#organization","name":"Poggi S.p.a. - Produttori di Silos dal 1945","url":"https:\/\/poggi.tesecom.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","contentUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","width":1484,"height":494,"caption":"Poggi S.p.a. - Produttori di Silos dal 1945"},"image":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/types\/prodotto"}],"version-history":[{"count":16,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121631\/revisions"}],"predecessor-version":[{"id":127414,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121631\/revisions\/127414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/media\/123865"}],"wp:attachment":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/media?parent=121631"}],"wp:term":[{"taxonomy":"categoria-prodotto","embeddable":true,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/categoria-prodotto?post=121631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}