{"id":121516,"date":"2025-12-02T11:59:02","date_gmt":"2025-12-02T10:59:02","guid":{"rendered":"https:\/\/poggi.tesecom.net\/prodotto\/decantatori-statici\/"},"modified":"2026-05-04T17:11:50","modified_gmt":"2026-05-04T15:11:50","slug":"decanteurs-statiques","status":"publish","type":"prodotto","link":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/","title":{"rendered":"D\u00e9canteurs statiques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"121516\" class=\"elementor elementor-121516 elementor-116176\" data-elementor-post-type=\"prodotto\">\n\t\t\t\t<div class=\"elementor-element elementor-element-545896f e-flex e-con-boxed e-con e-parent\" data-id=\"545896f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65e1e06 e-flex e-con-boxed e-con e-parent\" data-id=\"65e1e06\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-69107ec elementor-widget elementor-widget-breadcrumbs\" data-id=\"69107ec\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/poggi.tesecom.net\/fr\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4dd3a04 e-flex e-con-boxed e-con e-parent\" data-id=\"4dd3a04\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37cd95c elementor-widget elementor-widget-heading\" data-id=\"37cd95c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DECANTATEURS STATIQUES<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d46f4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c6d46f4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b890b15 e-flex e-con-boxed e-con e-parent\" data-id=\"b890b15\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5b6b2 elementor-widget elementor-widget-text-editor\" data-id=\"9c5b6b2\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Processus statique, gestion simplifi\u00e9e, r\u00e9sultats constants<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87ba655 e-flex e-con-boxed e-con e-parent\" data-id=\"87ba655\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f26faf3 e-con-full e-flex e-con e-child\" data-id=\"f26faf3\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5abac8 elementor-widget elementor-widget-image\" data-id=\"d5abac8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"691\" height=\"765\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-en-fonctionnement-Poggi-spa.webp\" class=\"attachment-full size-full wp-image-126210\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-en-fonctionnement-Poggi-spa.webp 691w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-en-fonctionnement-Poggi-spa-271x300.webp 271w\" sizes=\"(max-width: 691px) 100vw, 691px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82a3c4f e-con-full e-flex e-con e-child\" data-id=\"82a3c4f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-636a525 elementor-widget elementor-widget-heading\" data-id=\"636a525\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00c9CANTATEURS STATIQUES S\u00c9RIE S-DEC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60b489f elementor-widget elementor-widget-heading\" data-id=\"60b489f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caract\u00e9ristiques<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2b27f8 e-con-full e-flex e-con e-child\" data-id=\"e2b27f8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7829c8b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7829c8b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contatto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c0f2a4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0c0f2a4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#pdf\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-file-pdf\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M369.9 97.9L286 14C277 5 264.8-.1 252.1-.1H48C21.5 0 0 21.5 0 48v416c0 26.5 21.5 48 48 48h288c26.5 0 48-21.5 48-48V131.9c0-12.7-5.1-25-14.1-34zM332.1 128H256V51.9l76.1 76.1zM48 464V48h160v104c0 13.3 10.7 24 24 24h104v288H48zm250.2-143.7c-12.2-12-47-8.7-64.4-6.5-17.2-10.5-28.7-25-36.8-46.3 3.9-16.1 10.1-40.6 5.4-56-4.2-26.2-37.8-23.6-42.6-5.9-4.4 16.1-.4 38.5 7 67.1-10 23.9-24.9 56-35.4 74.4-20 10.3-47 26.2-51 46.2-3.3 15.8 26 55.2 76.1-31.2 22.4-7.4 46.8-16.5 68.4-20.1 18.9 10.2 41 17 55.8 17 25.5 0 28-28.2 17.5-38.7zm-198.1 77.8c5.1-13.7 24.5-29.5 30.4-35-19 30.3-30.4 35.7-30.4 35zm81.6-190.6c7.4 0 6.7 32.1 1.8 40.8-4.4-13.9-4.3-40.8-1.8-40.8zm-24.4 136.6c9.7-16.9 18-37 24.7-54.7 8.3 15.1 18.9 27.2 30.1 35.5-20.8 4.3-38.9 13.1-54.8 19.2zm131.6-5s-5 6-37.3-7.8c35.1-2.6 40.9 5.4 37.3 7.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Scarica il catalogo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc419ac elementor-widget elementor-widget-text-editor\" data-id=\"cc419ac\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tLes <strong>d\u00e9cantateurs statiques<\/strong>, \u00e9galement appel\u00e9s clarificateurs ou s\u00e9dimentateurs statiques, sont con\u00e7us pour offrir une solution simple, fiable et continue pour la s\u00e9paration solide-liquide dans les processus industriels. Bas\u00e9s sur un principe de s\u00e9dimentation naturelle (force de gravit\u00e9), ils fonctionnent sans organes mobiles, r\u00e9duisant les co\u00fbts de gestion et garantissant une continuit\u00e9 op\u00e9rationnelle maximale dans le temps.\n\nLes parties en contact avec le mat\u00e9riau \u00e0 traiter peuvent \u00eatre r\u00e9alis\u00e9es avec diff\u00e9rentes finitions, en fonction des caract\u00e9ristiques du produit \u00e0 s\u00e9dimenter.\n\nGr\u00e2ce \u00e0 leur simplicit\u00e9 de construction et \u00e0 un montage rapide, les d\u00e9cantateurs statiques Poggi s\u2019int\u00e8grent facilement dans des installations nouvelles ou existantes. Ils peuvent \u00eatre raccord\u00e9s directement \u00e0 des pompes d\u2019extraction, des silos \u00e0 boues, des presses \u00e0 filtres ou des bassins de collecte, les rendant id\u00e9aux pour les installations de lavage d\u2019inertes, le traitement des eaux us\u00e9es industrielles, le recyclage environnemental et de nombreuses autres applications.\n\nPolyvalents, robustes et efficaces, ils repr\u00e9sentent un choix intelligent pour ceux qui recherchent fiabilit\u00e9, gestion simplifi\u00e9e et une solution \u00e0 faible impact \u00e9nerg\u00e9tique.\n\nLes d\u00e9cantateurs statiques ou s\u00e9dimentateurs statiques repr\u00e9sentent <strong>une solution efficace et performante<\/strong> pour le traitement de l\u2019eau, am\u00e9liorant significativement la qualit\u00e9 de l\u2019eau gr\u00e2ce \u00e0 un processus de s\u00e9paration naturel et simple.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c313d4 e-flex e-con-boxed e-con e-parent\" data-id=\"0c313d4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e80525c elementor-widget elementor-widget-text-editor\" data-id=\"e80525c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9cantateurs statiques Poggi, depuis toujours, le choix professionnel<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ee7809 e-con-full e-flex e-con e-child\" data-id=\"8ee7809\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-79d0bbd e-con-full e-flex e-con e-child\" data-id=\"79d0bbd\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-640c8aa elementor-widget elementor-widget-text-editor\" data-id=\"640c8aa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Structure fixe galvanis\u00e9e ou peinte, avec parties en contact personnalisables selon le mat\u00e9riau trait\u00e9\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Syst\u00e8me de d\u00e9cantation naturelle, sans organes mobiles et avec un besoin r\u00e9duit de maintenance\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Adapt\u00e9s aux installations de lavage d\u2019inertes, au traitement des eaux us\u00e9es industrielles et au recyclage environnemental\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a79dd9 e-con-full e-flex e-con e-child\" data-id=\"5a79dd9\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39c28d3 elementor-widget elementor-widget-text-editor\" data-id=\"39c28d3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Facilit\u00e9 de montage et int\u00e9gration avec pompes, silos \u00e0 boues, presses \u00e0 filtres ou bassins de collecte, pour une gestion continue et automatisable des boues.\n\n<span style=\"color: #1a94d2;\"><strong>><\/strong><\/span> Solution \u00e0 faible consommation \u00e9nerg\u00e9tique, id\u00e9ale pour des installations n\u00e9cessitant fiabilit\u00e9 et simplicit\u00e9 de gestion\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1de962b e-flex e-con-boxed e-con e-parent\" data-id=\"1de962b\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80ae2b3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"80ae2b3\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-487e31d e-flex e-con-boxed e-con e-parent\" data-id=\"487e31d\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-231d5fb e-con-full e-flex e-con e-child\" data-id=\"231d5fb\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3fafa7 elementor-widget elementor-widget-heading\" data-id=\"b3fafa7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Polyvalence d\u2019application<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cc313a elementor-widget elementor-widget-heading\" data-id=\"5cc313a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une solution, de multiples secteurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83916c0 elementor-widget elementor-widget-text-editor\" data-id=\"83916c0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tL\u2019efficacit\u00e9 d\u2019un <strong>d\u00e9cantateur statique ou d\u2019un clarificateur statique<\/strong> ne d\u00e9pend pas seulement du principe de fonctionnement, mais surtout de la qualit\u00e9 de construction et de la fiabilit\u00e9 dans le temps. Les <strong>s\u00e9dimentateurs statiques<\/strong> Poggi sont con\u00e7us pour r\u00e9pondre \u00e0 ces exigences gr\u00e2ce \u00e0 une conception attentive aux d\u00e9tails : chaque \u00e9l\u00e9ment est optimis\u00e9 pour favoriser le rendement du traitement, simplifier l\u2019int\u00e9gration dans les lignes existantes et r\u00e9duire au minimum les interruptions op\u00e9rationnelles. Une solution concr\u00e8te pour garantir la stabilit\u00e9 du processus m\u00eame dans des conditions variables ou impr\u00e9visibles.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d2aeaa elementor-widget elementor-widget-text-editor\" data-id=\"3d2aeaa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Structure fixe galvanis\u00e9e ou peinte, avec parties en contact personnalisables selon le mat\u00e9riau trait\u00e9\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Syst\u00e8me de d\u00e9cantation naturelle, sans organes mobiles et avec un besoin r\u00e9duit de maintenance\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Adapt\u00e9s aux installations de lavage <strong>inertes<\/strong>, au traitement des eaux us\u00e9es industrielles et au recyclage environnemental\n\n<strong><span style=\"color: #1a94d2;\">><\/span><\/strong> Facilit\u00e9 de montage et int\u00e9gration avec pompes, silos \u00e0 boues, presses \u00e0 filtres ou bassins de collecte, pour une gestion continue et automatisable des boues\n\n<span style=\"color: #1a94d2;\"><strong>><\/strong><\/span> Solution \u00e0 faible consommation \u00e9nerg\u00e9tique, id\u00e9ale pour des installations n\u00e9cessitant <em>fiabilit\u00e9<\/em> et simplicit\u00e9 de gestion\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-558d19d e-con-full e-flex e-con e-child\" data-id=\"558d19d\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c5c870 elementor-widget elementor-widget-image\" data-id=\"9c5c870\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteurs-statiques-Poggi-spa.webp\" class=\"attachment-large size-large wp-image-126211\" alt=\"D\u00e9canteurs statiques Poggi spa\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteurs-statiques-Poggi-spa.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteurs-statiques-Poggi-spa-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ead1fb4 e-flex e-con-boxed e-con e-parent\" data-id=\"ead1fb4\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccbf73f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ccbf73f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d059f39 e-flex e-con-boxed e-con e-parent\" data-id=\"d059f39\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08757bd elementor-widget elementor-widget-text-editor\" data-id=\"08757bd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong>Fonctionnement et s\u00e9curit\u00e9<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c39f6e elementor-widget elementor-widget-text-editor\" data-id=\"5c39f6e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tDans les <strong>d\u00e9cantateurs statiques<\/strong>, l\u2019eau \u00e0 traiter est introduite dans la partie sup\u00e9rieure du d\u00e9cantateur et dirig\u00e9e \u00e0 l\u2019int\u00e9rieur d\u2019un cylindre vertical central, \u00e9galement appel\u00e9 tube de calme, qui s\u2019\u00e9tend jusqu\u2019au fond de la cuve. Ce syst\u00e8me guide le flux vers le bas et contr\u00f4le sa remont\u00e9e, assurant une distribution uniforme et un r\u00e9gime d\u2019\u00e9coulement stable de bas en haut.\n\nDe cette mani\u00e8re, les turbulences sont r\u00e9duites, la s\u00e9dimentation progressive des particules solides est favoris\u00e9e et l\u2019efficacit\u00e9 de la s\u00e9paration est am\u00e9lior\u00e9e. Les boues s\u2019accumulent au fond conique, d\u2019o\u00f9 elles peuvent \u00eatre \u00e9vacu\u00e9es par une sortie inf\u00e9rieure.\n\nL\u2019eau clarifi\u00e9e, en revanche, remonte jusqu\u2019\u00e0 la partie sup\u00e9rieure et est collect\u00e9e \u00e0 travers des canaux de trop-plein positionn\u00e9s le long du bord. Elle peut ensuite \u00eatre dirig\u00e9e vers les \u00e9tapes suivantes du traitement ou vers des bassins de stockage. Le processus se d\u00e9roule de mani\u00e8re continue.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1241b8a elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"1241b8a\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9db6fcf elementor-widget elementor-widget-elementskit-hotspot\" data-id=\"9db6fcf\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-hotspot.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"ekit-location-groups\" data-breakpoints=\"{&quot;mobile&quot;:767,&quot;tablet&quot;:1024}\">\n            <div class=\"ekit-map-image text-center\">\n                <img decoding=\"async\" width=\"1334\" height=\"1110\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-statiques.webp\" class=\"attachment-full size-full\" alt=\"d\u00e9canteurs statiques\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-statiques.webp 1334w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-statiques-300x250.webp 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-statiques-1024x852.webp 1024w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/decanteurs-statiques-768x639.webp 768w\" sizes=\"(max-width: 1334px) 100vw, 1334px\" \/>            <\/div>\n            <div class=\"ekit-location-wraper clearfix\">\n                \n<div class=\"ekit-location elementor-repeater-item-798c950 ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">COLLECTE DE L\u2019EAU CLARIFI\u00c9E<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>Dans la partie sup\u00e9rieure du d\u00e9cantateur statique est plac\u00e9 le d\u00e9versoir, un syst\u00e8me p\u00e9riph\u00e9rique \u00e0 trop-plein dont la fonction est de collecter l\u2019eau clarifi\u00e9e \u00e0 la fin du processus de s\u00e9paration. L\u2019eau, remontant lentement le long de la cuve gr\u00e2ce au flux contr\u00f4l\u00e9, atteint le d\u00e9versoir de mani\u00e8re uniforme, sans turbulence, garantissant une collecte r\u00e9guli\u00e8re et continue du liquide \u00e9pur\u00e9. Depuis le d\u00e9versoir, l\u2019eau clarifi\u00e9e est dirig\u00e9e vers un tuyau de sortie positionn\u00e9 \u00e0 l\u2019ext\u00e9rieur du d\u00e9cantateur, par lequel elle peut \u00eatre envoy\u00e9e vers des bassins de stockage, des recirculations de processus ou des traitements ult\u00e9rieurs. La g\u00e9om\u00e9trie et la disposition du d\u00e9versoir sont con\u00e7ues pour maintenir un niveau constant et maximiser la surface utile de trop-plein, optimisant ainsi l\u2019efficacit\u00e9 globale du syst\u00e8me.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n<div class=\"ekit-location elementor-repeater-item-1c7e8e6 ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">C\u00d4NE DE CHARGEMENT ET AJOUT DE FLOCCULANTS<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>Dans le c\u00f4ne de d\u00e9charge, situ\u00e9 dans la partie inf\u00e9rieure du d\u00e9cantateur statique, s\u2019accumulent les solides s\u00e9par\u00e9s par le flux remontant. Cette zone repr\u00e9sente le point de concentration maximale du mat\u00e9riau s\u00e9diment\u00e9 et peut \u00eatre \u00e9quip\u00e9e pour l\u2019ajout contr\u00f4l\u00e9 de floculants.<br \/>L\u2019ajout de floculants, via des syst\u00e8mes de dosage int\u00e9grables sur demande, am\u00e9liore l\u2019efficacit\u00e9 de la s\u00e9paration en favorisant l\u2019agr\u00e9gation des particules fines et en acc\u00e9l\u00e9rant la s\u00e9dimentation. Cette solution est particuli\u00e8rement utile en pr\u00e9sence de boues l\u00e9g\u00e8res ou de suspensions \u00e0 faible densit\u00e9, et permet d\u2019optimiser la vidange et la gestion des r\u00e9sidus.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n<div class=\"ekit-location elementor-repeater-item-aa874dd ekit-location-on-click hotspot-following-line-straight ekit_hotspot_follow_line_top auto  \" data-directions=\"{&quot;desktop&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;,&quot;mobile&quot;:&quot;ekit_hotspot_follow_line_top auto&quot;}\">\n    <div class=\"ekit-location_outer\">\n        <div class=\"ekit-hotspot-vertical-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n        <div class=\"media ekit-flex-column ekit-location_inner\">\n                            <div class='media-body'>\n                                        <h3 class=\"ekit-hotspot-title\">CYLINDRE DIFFUSEUR<\/h3>\n                                                            <div class='ekit-location-des'>\n                        <p>&gt; \u00c0 la base du cylindre central, o\u00f9 l\u2019eau est introduite dans le d\u00e9cantateur statique, se trouve le cylindre diffuseur, un composant fondamental pour garantir une distribution uniforme et contr\u00f4l\u00e9e du flux entrant.<\/p><p>Le diffuseur ralentit et uniformise le flux ascendant, \u00e9liminant les courants directs pouvant compromettre la s\u00e9dimentation. Gr\u00e2ce \u00e0 cette g\u00e9om\u00e9trie, l\u2019eau commence \u00e0 remonter de mani\u00e8re homog\u00e8ne et \u00e0 vitesse r\u00e9duite, cr\u00e9ant les conditions id\u00e9ales pour la s\u00e9paration des particules solides.<\/p><p>Le cylindre diffuseur contribue ainsi \u00e0 stabiliser le flux interne, r\u00e9duire les turbulences et augmenter l\u2019efficacit\u00e9 du d\u00e9cantateur, m\u00eame en pr\u00e9sence de charges variables ou de mat\u00e9riaux particuli\u00e8rement fins.<\/p>                    <\/div>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"ekit-location_indicator\">\n                    <div class=\"ekit_hotspot_pulse_1\"><\/div>\n            <div class=\"ekit_hotspot_pulse_2\"><\/div>\n                <div class=\"ekit-hotspot-horizontal-line\">\n                            <div class=\"ekit_hotspot_arrow\"><\/div>\n                    <\/div>\n    <\/div>\n<\/div>            <\/div><!-- .location-wraper END -->\n        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b821372 e-flex e-con-boxed e-con e-parent\" data-id=\"b821372\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-402988e elementor-widget elementor-widget-heading\" data-id=\"402988e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gestion des flux de mati\u00e8re<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1005983 e-flex e-con-boxed e-con e-parent\" data-id=\"1005983\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b05f68b e-con-full e-flex e-con e-child\" data-id=\"b05f68b\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-025f097 elementor-widget elementor-widget-heading\" data-id=\"025f097\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">VIDANGE<\/span> DES BOUDES<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3cfe2b elementor-widget elementor-widget-text-editor\" data-id=\"b3cfe2b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #1a94d2;\"><strong>SYST\u00c8ME DE S\u00c9DIMENTATION<\/strong><\/span>\n\u00c0 l\u2019int\u00e9rieur du s\u00e9dimentateur statique, le flux ralenti permet la s\u00e9dimentation naturelle des solides en suspension. Les boues s\u2019accumulent progressivement au fond, se s\u00e9parant de l\u2019eau clarifi\u00e9e.\n\n<span style=\"color: #1a94d2;\"><strong>CONDUIT DE SORTIE INF\u00c9RIEURE<\/strong><\/span>\nLes mat\u00e9riaux d\u00e9cant\u00e9s sont \u00e9vacu\u00e9s via une sortie situ\u00e9e au fond du d\u00e9cantateur. Le syst\u00e8me est con\u00e7u pour \u00eatre raccord\u00e9 directement \u00e0 des pompes, silos \u00e0 boues ou installations de d\u00e9shydratation.\n\n<span style=\"color: #1a94d2;\"><strong>GESTION DU FLUX DE BOUDES<\/strong><\/span>\nLa vidange peut \u00eatre continue ou contr\u00f4l\u00e9e de mani\u00e8re cyclique, selon le d\u00e9bit et le processus en aval. L\u2019op\u00e9rateur peut r\u00e9gler la vidange via des vannes, temporisateurs ou commandes \u00e0 distance, en fonction des besoins de l\u2019installation.\n\n<span style=\"color: #1a94d2;\"><strong>STABILIT\u00c9 DU PROCESSUS<\/strong><\/span>\nL\u2019absence de parties mobiles garantit une continuit\u00e9 op\u00e9rationnelle, r\u00e9duisant au minimum les pannes, blocages ou besoins de maintenance.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-57ca1b1 e-con-full e-flex e-con e-child\" data-id=\"57ca1b1\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-019d9d4 elementor-widget elementor-widget-image\" data-id=\"019d9d4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-realise-par-Poggi-spa.webp\" class=\"attachment-large size-large wp-image-126212\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-realise-par-Poggi-spa.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-realise-par-Poggi-spa-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b85695 e-flex e-con-boxed e-con e-parent\" data-id=\"1b85695\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e5a95ab e-con-full e-flex e-con e-child\" data-id=\"e5a95ab\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f70e62f elementor-widget elementor-widget-image\" data-id=\"f70e62f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-Poggi-spa.webp\" class=\"attachment-large size-large wp-image-126214\" alt=\"D\u00e9canteur statique Poggi spa\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-Poggi-spa.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-Poggi-spa-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ee205ee e-con-full e-flex e-con e-child\" data-id=\"ee205ee\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89287a9 elementor-widget elementor-widget-heading\" data-id=\"89287a9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">INT\u00c9GRATION<\/span> DANS L\u2019INSTALLATION<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13db0b2 elementor-widget elementor-widget-text-editor\" data-id=\"13db0b2\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">RACCORDEMENT AUX POMPES D\u2019EXTRACTION<\/span><\/strong>\nLe fond du d\u00e9cantateur peut \u00eatre pr\u00e9par\u00e9 pour le raccordement direct \u00e0 des pompes submersibles ou des pompes de transfert de boues, facilitant l\u2019alimentation vers les installations en aval.\n\n<strong><span style=\"color: #1a94d2;\">COMPATIBILIT\u00c9 AVEC LA PRESSE \u00c0 FILTRE<\/span><\/strong>\nLe flux de boues sortant du d\u00e9cantateur peut \u00eatre dirig\u00e9 vers un bassin de stockage avec agitateur plac\u00e9 en amont de la presse \u00e0 filtre, rendant le syst\u00e8me id\u00e9al pour alimenter de mani\u00e8re constante les unit\u00e9s de d\u00e9shydratation et r\u00e9duire les volumes de mat\u00e9riau \u00e0 \u00e9liminer.\n\n<span style=\"color: #1a94d2;\"><strong>RETOUR DE L\u2019EAU CLARIFI\u00c9E<\/strong><\/span>\nL\u2019eau \u00e9pur\u00e9e peut \u00eatre dirig\u00e9e vers des r\u00e9servoirs de collecte ou r\u00e9introduite dans le cycle de production, fermant ainsi le circuit de lavage ou de traitement de mani\u00e8re efficace et durable.\n\n<strong><span style=\"color: #1a94d2;\">S\u00c9CURIT\u00c9 OP\u00c9RATIONNELLE ET FLUX CONTR\u00d4L\u00c9<\/span><\/strong>\nPour les installations \u00e0 haute capacit\u00e9, des accessoires de s\u00e9curit\u00e9 tels que vannes de blocage, capteurs d\u2019ouverture contr\u00f4l\u00e9e et syst\u00e8mes anti-obstruction sont disponibles, garantissant continuit\u00e9 op\u00e9rationnelle et conformit\u00e9 r\u00e9glementaire.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a32c797 e-flex e-con-boxed e-con e-parent\" data-id=\"a32c797\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a540948 e-con-full e-flex e-con e-child\" data-id=\"a540948\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97b4bcb elementor-widget elementor-widget-heading\" data-id=\"97b4bcb\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><span class=\"blue\">GESTION<\/span> ET CONTR\u00d4LE OP\u00c9RATIONNEL<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d4696f elementor-widget elementor-widget-text-editor\" data-id=\"2d4696f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<strong><span style=\"color: #1a94d2;\">SYST\u00c8ME DE SURVEILLANCE<\/span><\/strong>\nDes indicateurs de niveau, sondes et capteurs pour le contr\u00f4le du remplissage et la v\u00e9rification de la densit\u00e9 des boues peuvent \u00eatre int\u00e9gr\u00e9s sur demande.\n\n<strong><span style=\"color: #1a94d2;\">AUTOMATISATION ET INTERFACE \u00c0 DISTANCE<\/span><\/strong>\nSur demande, les clarificateurs statiques Poggi peuvent \u00eatre connect\u00e9s \u00e0 des syst\u00e8mes de contr\u00f4le centralis\u00e9s pour la gestion automatique des vannes de vidange, l\u2019enregistrement des cycles et l\u2019interaction avec les pompes ou silos.\n\n<strong><span style=\"color: #1a94d2;\">GESTION MANUELLE SIMPLIFI\u00c9E<\/span><\/strong>\nPour les installations non automatis\u00e9es, le d\u00e9cantateur peut \u00eatre \u00e9quip\u00e9 de vannes de vidange manuelles plac\u00e9es en position accessible et con\u00e7ues pour un usage fr\u00e9quent et s\u00fbr. Cette solution est id\u00e9ale pour des installations mobiles ou de faible complexit\u00e9, o\u00f9 la priorit\u00e9 est la fiabilit\u00e9 m\u00e9canique et la simplicit\u00e9 d\u2019utilisation sans \u00e9lectronique.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb07381 e-con-full e-flex e-con e-child\" data-id=\"bb07381\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d471ff elementor-widget elementor-widget-image\" data-id=\"0d471ff\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"654\" height=\"423\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-construction.webp\" class=\"attachment-large size-large wp-image-126215\" alt=\"D\u00e9canteur statique construction\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-construction.webp 654w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-statique-construction-300x194.webp 300w\" sizes=\"(max-width: 654px) 100vw, 654px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e43eba8 e-flex e-con-boxed e-con e-parent\" data-id=\"e43eba8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b82f0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a7b82f0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8f2772c elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"8f2772c\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfdf3b4 elementor-widget elementor-widget-heading\" data-id=\"dfdf3b4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9tails techniques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc9fcef elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"dc9fcef\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d353adc e-n-tabs-mobile elementor-widget elementor-widget-n-tabs\" data-id=\"d353adc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"nested-tabs.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-tabs\" data-widget-number=\"221592284\" aria-label=\"Onglets. Ouvrez des \u00e9l\u00e9ments avec Entrer ou Espace, fermez-les avec Echape et naviguez \u00e0 l&#039;aide des touches fl\u00e9ch\u00e9es.\">\n\t\t\t<div class=\"e-n-tabs-heading\" role=\"tablist\">\n\t\t\t\t\t<button id=\"e-n-tab-title-2215922841\" class=\"e-n-tab-title\" aria-selected=\"true\" data-tab-index=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"e-n-tab-content-2215922841\" style=\"--n-tabs-title-order: 1;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 35\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2215922842\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2215922842\" style=\"--n-tabs-title-order: 2;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 48\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2215922843\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2215922843\" style=\"--n-tabs-title-order: 3;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 61\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2215922844\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2215922844\" style=\"--n-tabs-title-order: 4;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 76\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2215922845\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"5\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2215922845\" style=\"--n-tabs-title-order: 5;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 95\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t<button id=\"e-n-tab-title-2215922846\" class=\"e-n-tab-title\" aria-selected=\"false\" data-tab-index=\"6\" role=\"tab\" tabindex=\"-1\" aria-controls=\"e-n-tab-content-2215922846\" style=\"--n-tabs-title-order: 6;\">\n\t\t\t\t\t<span class=\"e-n-tab-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"icon icon-down-arrow1\"><\/i>\t\t\t<i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i>\t\t<\/span>\n\t\t\t\t\t<span class=\"e-n-tab-title-text\">\n\t\t\t\tD\u00e9cantateurs statiques s-dec 120\t\t\t<\/span>\n\t\t<\/button>\n\t\t\t\t\t<\/div>\n\t\t\t<div class=\"e-n-tabs-content\">\n\t\t\t\t<div id=\"e-n-tab-content-2215922841\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922841\" data-tab-index=\"1\" style=\"--n-tabs-title-order: 1;\" class=\"e-active elementor-element elementor-element-7f6667f e-con-full e-flex e-con e-child\" data-id=\"7f6667f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9df4a1b elementor-widget elementor-widget-image\" data-id=\"9df4a1b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"605\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-35.webp\" class=\"attachment-medium_large size-medium_large wp-image-126561\" alt=\"D\u00e9canteur Statique Donn\u00e9es Techniques S Dec 35\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-35.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-35-300x272.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a09d409 elementor-widget elementor-widget-image\" data-id=\"a09d409\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2215922842\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922842\" data-tab-index=\"2\" style=\"--n-tabs-title-order: 2;\" class=\" elementor-element elementor-element-69bcb39 e-con-full e-flex e-con e-child\" data-id=\"69bcb39\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1bbdb89 elementor-widget elementor-widget-image\" data-id=\"1bbdb89\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"501\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-48.webp\" class=\"attachment-medium_large size-medium_large wp-image-126565\" alt=\"D\u00e9canteur Statique Donn\u00e9es Techniques S Dec 48\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-48.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-48-300x225.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe72d4 elementor-widget elementor-widget-image\" data-id=\"bfe72d4\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2215922843\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922843\" data-tab-index=\"3\" style=\"--n-tabs-title-order: 3;\" class=\" elementor-element elementor-element-30e831c e-con-full e-flex e-con e-child\" data-id=\"30e831c\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86c7195 elementor-widget elementor-widget-image\" data-id=\"86c7195\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"501\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-61.webp\" class=\"attachment-medium_large size-medium_large wp-image-126566\" alt=\"D\u00e9canteur Statique Donn\u00e9es Techniques S Dec 61\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-61.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-61-300x225.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d36c48 elementor-widget elementor-widget-image\" data-id=\"2d36c48\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2215922844\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922844\" data-tab-index=\"4\" style=\"--n-tabs-title-order: 4;\" class=\" elementor-element elementor-element-044211a e-con-full e-flex e-con e-child\" data-id=\"044211a\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-41004c5 elementor-widget elementor-widget-image\" data-id=\"41004c5\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"501\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-76.webp\" class=\"attachment-medium_large size-medium_large wp-image-126567\" alt=\"D\u00e9canteur Statique Donn\u00e9es Techniques S Dec 76\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-76.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-76-300x225.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4559d01 elementor-widget elementor-widget-image\" data-id=\"4559d01\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2215922845\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922845\" data-tab-index=\"5\" style=\"--n-tabs-title-order: 5;\" class=\" elementor-element elementor-element-ee3f51c e-con-full e-flex e-con e-child\" data-id=\"ee3f51c\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04e0a7b elementor-widget elementor-widget-image\" data-id=\"04e0a7b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"501\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-95.webp\" class=\"attachment-medium_large size-medium_large wp-image-126572\" alt=\"D\u00e9canteur Statique Donn\u00e9es Techniques S Dec 95\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-95.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-95-300x225.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-635ab51 elementor-widget elementor-widget-image\" data-id=\"635ab51\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div id=\"e-n-tab-content-2215922846\" role=\"tabpanel\" aria-labelledby=\"e-n-tab-title-2215922846\" data-tab-index=\"6\" style=\"--n-tabs-title-order: 6;\" class=\" elementor-element elementor-element-3e52d56 e-con-full e-flex e-con e-child\" data-id=\"3e52d56\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ab68a7 elementor-widget elementor-widget-image\" data-id=\"1ab68a7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"501\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-120.webp\" class=\"attachment-medium_large size-medium_large wp-image-126568\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-120.webp 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Donnees-Techniques-S-Dec-120-300x225.webp 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e4c185 elementor-widget elementor-widget-image\" data-id=\"6e4c185\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"357\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg\" class=\"attachment-medium_large size-medium_large wp-image-126556\" alt=\"D\u00e9canteur Statique Dessin Technique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique.jpg 667w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Decanteur-Statique-Dessin-Technique-300x161.jpg 300w\" sizes=\"(max-width: 667px) 100vw, 667px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d187bcd e-flex e-con-boxed e-con e-parent\" data-id=\"d187bcd\" data-element_type=\"container\" id=\"pdf\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7d358b9 e-con-full e-flex e-con e-child\" data-id=\"7d358b9\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a5a655 e-con-full e-flex e-con e-child\" data-id=\"9a5a655\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5874bcc e-flex e-con-boxed e-con e-parent\" data-id=\"5874bcc\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-83d8e92 e-con-full e-flex e-con e-child\" data-id=\"83d8e92\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-c41c5e6 e-con-full e-flex e-con e-child\" data-id=\"c41c5e6\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2784fed elementor-widget elementor-widget-heading\" data-id=\"2784fed\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESSOIRES ET OPTIONS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19ad44c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"19ad44c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Une gamme compl\u00e8te d\u2019accessoires et d\u2019options pour personnaliser chaque produit. Des syst\u00e8mes de mesure, filtration, s\u00e9curit\u00e9, extraction et contr\u00f4le permettent d\u2019adapter les produits silos aux besoins op\u00e9rationnels sp\u00e9cifiques, garantissant une efficacit\u00e9 maximale et une continuit\u00e9 de fonctionnement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8bd9019 e-con-full e-flex e-con e-child\" data-id=\"8bd9019\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e167f elementor-arrows-position-inside elementor-widget elementor-widget-n-carousel\" data-id=\"11e167f\" data-element_type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;aee3b0e&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;127c43a&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;1facfc3&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;85f0f52&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;37c733e&quot;},{&quot;slide_title&quot;:&quot;Slide #1&quot;,&quot;_id&quot;:&quot;988cf31&quot;}],&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b966da1 e-flex e-con-boxed e-con e-child\" data-id=\"b966da1\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba8250f elementor-widget elementor-widget-image\" data-id=\"ba8250f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"518\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png\" class=\"attachment-large size-large wp-image-121620\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png 932w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-300x194.png 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-768x498.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fafb040 elementor-widget elementor-widget-heading\" data-id=\"fafb040\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REV\u00caTEMENTS\nINTERNES SP\u00c9CIAUX<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c7a01f8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7a01f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#RIVESTIMENTI_INTERNI_SPECIALI\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7454eb e-flex e-con-boxed e-con e-child\" data-id=\"c7454eb\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-429d983 elementor-widget elementor-widget-image\" data-id=\"429d983\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"518\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png\" class=\"attachment-large size-large wp-image-121620\" alt=\"\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1.png 932w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-300x194.png 300w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/11\/Asset-1-1-768x498.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fbe385 elementor-widget elementor-widget-heading\" data-id=\"9fbe385\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SYST\u00c8MES DE CHAUFFAGE OU D\u2019ISOLATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38b1d2c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"38b1d2c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#SISTEMI_DI_RISCALDAMENTO_O_COIBENTAZIONE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cda5879 e-flex e-con-boxed e-con e-child\" data-id=\"cda5879\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b517299 elementor-widget elementor-widget-image\" data-id=\"b517299\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp\" class=\"attachment-large size-large wp-image-124109\" alt=\"garde-corps-\u00e9chelles-silos\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/garde-corps-echelles-silos-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4a668 elementor-widget elementor-widget-heading\" data-id=\"ae4a668\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ACCESSOIRES\nDE S\u00c9CURIT\u00c9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-afa3e35 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"afa3e35\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#ACCESSORI_DI_SICUREZZA\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e3b19f e-flex e-con-boxed e-con e-child\" data-id=\"3e3b19f\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66f73dd elementor-widget elementor-widget-image\" data-id=\"66f73dd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique.webp\" class=\"attachment-large size-large wp-image-124095\" alt=\"armoire-\u00e9lectrique\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/armoire-electrique-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f502f8 elementor-widget elementor-widget-heading\" data-id=\"1f502f8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">COMMANDES \u00c9LECTRIQUES\nET INTERFACES OP\u00c9RATOIRES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf85e7f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cf85e7f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#COMANDI_ELETTRICI_E_INTERFACCE_OPERATIVE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8bb7c8 e-flex e-con-boxed e-con e-child\" data-id=\"c8bb7c8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb0839d elementor-widget elementor-widget-image\" data-id=\"fb0839d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau.webp\" class=\"attachment-large size-large wp-image-124113\" alt=\"ndicateur-niveau\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/ndicateur-niveau-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f55ff27 elementor-widget elementor-widget-heading\" data-id=\"f55ff27\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTR\u00d4LE DES NIVEAUX\nET SURVEILLANCE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-effc55d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"effc55d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#CONTROLLO_LIVELLI_E_MONITORAGGIO\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"6\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 6\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd48ba8 e-flex e-con-boxed e-con e-child\" data-id=\"bd48ba8\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f4d206a elementor-widget elementor-widget-image\" data-id=\"f4d206a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"378\" height=\"245\" src=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Parapetti-e-scale-sicurezza-per-silos-1.webp\" class=\"attachment-large size-large wp-image-121562\" alt=\"Parapetti-e-scale-sicurezza-per-silos\" srcset=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Parapetti-e-scale-sicurezza-per-silos-1.webp 378w, https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/12\/Parapetti-e-scale-sicurezza-per-silos-1-300x194.webp 300w\" sizes=\"(max-width: 378px) 100vw, 378px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71bea14 elementor-widget elementor-widget-heading\" data-id=\"71bea14\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fonctionnalit\u00e9s suppl\u00e9mentaires\npour la Sant\u00e9 et la S\u00e9curit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5807bd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c5807bd\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/poggi.tesecom.net\/accessori-e-optionals-decantatori-statici\/#Funzionalit\u00e0_Extra_per_Salute_e_Sicurezza\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Previous\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Next\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a51841 e-flex e-con-boxed e-con e-parent\" data-id=\"3a51841\" data-element_type=\"container\" id=\"contatto\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90e5ef7 elementor-widget elementor-widget-heading\" data-id=\"90e5ef7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTACTEZ-NOUS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24cc001 elementor-button-align-center elementor-widget__width-initial elementor-widget elementor-widget-global elementor-global-123119 elementor-global-162 elementor-widget-form\" data-id=\"24cc001\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"121516\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"24cc001\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Poggi S.p.a.\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Nom\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_a5fb305 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_a5fb305\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tCognome\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_a5fb305]\" id=\"form-field-field_a5fb305\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Last name\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_5d4c6bb elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5d4c6bb\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tAzienda\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_5d4c6bb]\" id=\"form-field-field_5d4c6bb\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Entreprise\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_8d6aee9 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8d6aee9\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tNazione\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_8d6aee9]\" id=\"form-field-field_8d6aee9\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Pays\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-field_f9519d3 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_f9519d3\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tTelefono\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[field_f9519d3]\" id=\"form-field-field_f9519d3\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"T\u00e9l\u00e9phone\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tMessaggio\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Message\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-checkbox elementor-field-group elementor-column elementor-field-group-field_3ce8930 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3ce8930\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tInscription\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<div class=\"elementor-field-subgroup  \"><span class=\"elementor-field-option\"><input type=\"checkbox\" value=\"Inscription \u00e0 la newsletter Politique de confidentialit\u00e9\" id=\"form-field-field_3ce8930-0\" name=\"form_fields[field_3ce8930]\"> <label for=\"form-field-field_3ce8930-0\">Inscription \u00e0 la newsletter Politique de confidentialit\u00e9<\/label><\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_5f5db32 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_5f5db32\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tInscription\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_5f5db32]\" id=\"form-field-field_5f5db32\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_5f5db32\">Confidentialit\u00e9 Si vous ne consentez pas au traitement des donn\u00e9es il ne sera pas possible de r\u00e9pondre \u00e0 votre demande.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer une demande<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bca3cb3 e-con-full e-flex e-con e-parent\" data-id=\"bca3cb3\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17d8f14 elementor-widget elementor-widget-template\" data-id=\"17d8f14\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"122690\" class=\"elementor elementor-122690 elementor-118976 elementor-118976\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2be0d9c4 e-flex e-con-boxed e-con e-parent\" data-id=\"2be0d9c4\" data-element_type=\"container\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef445d elementor-widget elementor-widget-heading\" data-id=\"2ef445d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S\u2019inscrire \u00e0 la newsletter<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51defb6d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"51defb6d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e4b2865 elementor-widget__width-inherit elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"2e4b2865\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"122690\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"2e4b2865\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Transformation du plastique - Poggi S.p.a.\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"121241\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label elementor-screen-only\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Adresse e-mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_e04bf5a elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_e04bf5a]\" id=\"form-field-field_e04bf5a\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_e04bf5a\">J\u2019ai pris connaissance de la politique de confidentialit\u00e9 et j\u2019accepte le traitement des donn\u00e9es.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S\u2019inscrire<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DecaD\u00e9canteurs statiques pour la s\u00e9paration solide-liquide bas\u00e9e sur la s\u00e9dimentation naturelle, sans pi\u00e8ces mobiles. Offrent une structure robuste, de faibles besoins de maintenance et une int\u00e9gration facile dans les installations de traitement des eaux et de recyclage industriel.<\/p>\n","protected":false},"featured_media":123866,"template":"elementor_header_footer","meta":{"_acf_changed":false},"categoria-prodotto":[],"class_list":["post-121516","prodotto","type-prodotto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi<\/title>\n<meta name=\"description\" content=\"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi\" \/>\n<meta property=\"og:description\" content=\"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Poggi S.p.a.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-04T15:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1034\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/\",\"name\":\"D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi\",\"isPartOf\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp\",\"datePublished\":\"2025-12-02T10:59:02+00:00\",\"dateModified\":\"2026-05-04T15:11:50+00:00\",\"description\":\"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.\",\"breadcrumb\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage\",\"url\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp\",\"contentUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp\",\"width\":1034,\"height\":672,\"caption\":\"D\u00e9canteur statique\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poggi.tesecom.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9canteurs statiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#website\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poggi.tesecom.net\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#organization\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"url\":\"https:\/\/poggi.tesecom.net\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"contentUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"width\":1484,\"height\":494,\"caption\":\"Poggi S.p.a. - Produttori di Silos dal 1945\"},\"image\":{\"@id\":\"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi","description":"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi","og_description":"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.","og_url":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/","og_site_name":"Poggi S.p.a.","article_modified_time":"2026-05-04T15:11:50+00:00","og_image":[{"width":1034,"height":672,"url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/","url":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/","name":"D\u00e9canteurs statiques pour s\u00e9paration solide-liquide | Poggi","isPartOf":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage"},"image":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage"},"thumbnailUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp","datePublished":"2025-12-02T10:59:02+00:00","dateModified":"2026-05-04T15:11:50+00:00","description":"D\u00e9canteurs statiques et clarificateurs Poggi pour la s\u00e9paration solide-liquide dans les processus industriels. Solutions fiables sans organes en mouvement.","breadcrumb":{"@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#primaryimage","url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp","contentUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2026\/04\/Decanteur-statique.webp","width":1034,"height":672,"caption":"D\u00e9canteur statique"},{"@type":"BreadcrumbList","@id":"https:\/\/poggi.tesecom.net\/fr\/prodotto\/decanteurs-statiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poggi.tesecom.net\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9canteurs statiques"}]},{"@type":"WebSite","@id":"https:\/\/poggi.tesecom.net\/fr\/#website","url":"https:\/\/poggi.tesecom.net\/fr\/","name":"Poggi S.p.a. - Produttori di Silos dal 1945","description":"","publisher":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poggi.tesecom.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/poggi.tesecom.net\/fr\/#organization","name":"Poggi S.p.a. - Produttori di Silos dal 1945","url":"https:\/\/poggi.tesecom.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","contentUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","width":1484,"height":494,"caption":"Poggi S.p.a. - Produttori di Silos dal 1945"},"image":{"@id":"https:\/\/poggi.tesecom.net\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto"}],"about":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/types\/prodotto"}],"version-history":[{"count":28,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121516\/revisions"}],"predecessor-version":[{"id":127408,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/prodotto\/121516\/revisions\/127408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/media\/123866"}],"wp:attachment":[{"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/media?parent=121516"}],"wp:term":[{"taxonomy":"categoria-prodotto","embeddable":true,"href":"https:\/\/poggi.tesecom.net\/fr\/wp-json\/wp\/v2\/categoria-prodotto?post=121516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}