{"id":42,"count":2,"description":"","link":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/","name":"Products and solutions","slug":"products-and-solutions","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Products and solutions Archivi - Poggi S.p.a.<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Products and solutions Archivi - Poggi S.p.a.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/\" \/>\n<meta property=\"og:site_name\" content=\"Poggi S.p.a.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/\",\"url\":\"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/\",\"name\":\"Products and solutions Archivi - Poggi S.p.a.\",\"isPartOf\":{\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/poggi.tesecom.net\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products and solutions\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#website\",\"url\":\"https:\/\/poggi.tesecom.net\/en\/\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/poggi.tesecom.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#organization\",\"name\":\"Poggi S.p.a. - Produttori di Silos dal 1945\",\"url\":\"https:\/\/poggi.tesecom.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"contentUrl\":\"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp\",\"width\":1484,\"height\":494,\"caption\":\"Poggi S.p.a. - Produttori di Silos dal 1945\"},\"image\":{\"@id\":\"https:\/\/poggi.tesecom.net\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Products and solutions Archivi - Poggi S.p.a.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Products and solutions Archivi - Poggi S.p.a.","og_url":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/","og_site_name":"Poggi S.p.a.","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/","url":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/","name":"Products and solutions Archivi - Poggi S.p.a.","isPartOf":{"@id":"https:\/\/poggi.tesecom.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/poggi.tesecom.net\/en\/category\/products-and-solutions\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/poggi.tesecom.net\/en\/"},{"@type":"ListItem","position":2,"name":"Products and solutions"}]},{"@type":"WebSite","@id":"https:\/\/poggi.tesecom.net\/en\/#website","url":"https:\/\/poggi.tesecom.net\/en\/","name":"Poggi S.p.a. - Produttori di Silos dal 1945","description":"","publisher":{"@id":"https:\/\/poggi.tesecom.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/poggi.tesecom.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/poggi.tesecom.net\/en\/#organization","name":"Poggi S.p.a. - Produttori di Silos dal 1945","url":"https:\/\/poggi.tesecom.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/poggi.tesecom.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","contentUrl":"https:\/\/poggi.tesecom.net\/wp-content\/uploads\/2025\/10\/Logo_2025.webp","width":1484,"height":494,"caption":"Poggi S.p.a. - Produttori di Silos dal 1945"},"image":{"@id":"https:\/\/poggi.tesecom.net\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/poggi.tesecom.net\/en\/wp-json\/wp\/v2\/categories\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poggi.tesecom.net\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/poggi.tesecom.net\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/poggi.tesecom.net\/en\/wp-json\/wp\/v2\/posts?categories=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}